{"id":22599,"date":"2021-10-28T13:22:52","date_gmt":"2021-10-28T13:22:52","guid":{"rendered":"https:\/\/biraghi.it\/stores\/spazio-conad-268\/"},"modified":"2021-10-28T13:22:52","modified_gmt":"2021-10-28T13:22:52","slug":"spazio-conad-268","status":"publish","type":"wpsl_stores","link":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/","title":{"rendered":"SPAZIO CONAD"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13446,"featured_media":0,"template":"","wpsl_store_category":[95,83],"class_list":["post-22599","wpsl_stores","type-wpsl_stores","status-publish","hentry","wpsl_store_category-abruzzo-granricotta","wpsl_store_category-granricotta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SPAZIO CONAD - Biraghi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPAZIO CONAD - Biraghi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/\" \/>\n<meta property=\"og:site_name\" content=\"Biraghi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FormaggiBiraghi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/\",\"url\":\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/\",\"name\":\"SPAZIO CONAD - Biraghi\",\"isPartOf\":{\"@id\":\"https:\/\/biraghi.it\/en\/#website\"},\"datePublished\":\"2021-10-28T13:22:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/biraghi.it\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SPAZIO CONAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/biraghi.it\/en\/#website\",\"url\":\"https:\/\/biraghi.it\/en\/\",\"name\":\"Biraghi\",\"description\":\"Qualit\u00e0 italiana dal 1934\",\"publisher\":{\"@id\":\"https:\/\/biraghi.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/biraghi.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/biraghi.it\/en\/#organization\",\"name\":\"Biraghi\",\"url\":\"https:\/\/biraghi.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/biraghi.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/biraghi.it\/wp-content\/uploads\/2023\/02\/logo-biraghi.svg\",\"contentUrl\":\"https:\/\/biraghi.it\/wp-content\/uploads\/2023\/02\/logo-biraghi.svg\",\"width\":1,\"height\":1,\"caption\":\"Biraghi\"},\"image\":{\"@id\":\"https:\/\/biraghi.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FormaggiBiraghi\",\"https:\/\/www.instagram.com\/formaggi_biraghi\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPAZIO CONAD - Biraghi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/","og_locale":"en_US","og_type":"article","og_title":"SPAZIO CONAD - Biraghi","og_url":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/","og_site_name":"Biraghi","article_publisher":"https:\/\/www.facebook.com\/FormaggiBiraghi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/","url":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/","name":"SPAZIO CONAD - Biraghi","isPartOf":{"@id":"https:\/\/biraghi.it\/en\/#website"},"datePublished":"2021-10-28T13:22:52+00:00","breadcrumb":{"@id":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/biraghi.it\/en\/stores\/spazio-conad-268\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biraghi.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"SPAZIO CONAD"}]},{"@type":"WebSite","@id":"https:\/\/biraghi.it\/en\/#website","url":"https:\/\/biraghi.it\/en\/","name":"Biraghi","description":"Qualit\u00e0 italiana dal 1934","publisher":{"@id":"https:\/\/biraghi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biraghi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/biraghi.it\/en\/#organization","name":"Biraghi","url":"https:\/\/biraghi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biraghi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/biraghi.it\/wp-content\/uploads\/2023\/02\/logo-biraghi.svg","contentUrl":"https:\/\/biraghi.it\/wp-content\/uploads\/2023\/02\/logo-biraghi.svg","width":1,"height":1,"caption":"Biraghi"},"image":{"@id":"https:\/\/biraghi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FormaggiBiraghi","https:\/\/www.instagram.com\/formaggi_biraghi"]}]}},"_links":{"self":[{"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/wpsl_stores\/22599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/wpsl_stores"}],"about":[{"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/types\/wpsl_stores"}],"author":[{"embeddable":true,"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/users\/13446"}],"version-history":[{"count":0,"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/wpsl_stores\/22599\/revisions"}],"wp:attachment":[{"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/media?parent=22599"}],"wp:term":[{"taxonomy":"wpsl_store_category","embeddable":true,"href":"https:\/\/biraghi.it\/en\/wp-json\/wp\/v2\/wpsl_store_category?post=22599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}